{"id":47997,"date":"2016-10-13T05:08:46","date_gmt":"2016-10-13T05:08:46","guid":{"rendered":"http:\/\/localhost\/wordpress\/2016\/10\/13\/%e0%b8%aa%e0%b8%a1%e0%b8%84%e0%b8%b4%e0%b8%94%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%95-%e0%b9%82%e0%b8%94%e0%b8%a2%e0%b8%99%e0%b8%b2%e0%b8%87%e0%b9%80%e0%b8%9e%e0%b9%87%e0%b8%8d\/"},"modified":"2016-10-13T05:08:46","modified_gmt":"2016-10-13T05:08:46","slug":"%e0%b8%aa%e0%b8%a1%e0%b8%84%e0%b8%b4%e0%b8%94%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%95-%e0%b9%82%e0%b8%94%e0%b8%a2%e0%b8%99%e0%b8%b2%e0%b8%87%e0%b9%80%e0%b8%9e%e0%b9%87%e0%b8%8d","status":"publish","type":"post","link":"https:\/\/www.thailandcompanydirectory.com\/factory\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5\/%e0%b8%aa%e0%b8%a1%e0%b8%84%e0%b8%b4%e0%b8%94%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%95-%e0%b9%82%e0%b8%94%e0%b8%a2%e0%b8%99%e0%b8%b2%e0%b8%87%e0%b9%80%e0%b8%9e%e0%b9%87%e0%b8%8d","title":{"rendered":"\u0e2a\u0e21\u0e04\u0e34\u0e14\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e42\u0e14\u0e22\u0e19\u0e32\u0e07\u0e40\u0e1e\u0e47\u0e0d\u0e28\u0e23\u0e35 \u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 &#8211; \u0e40\u0e25\u0e22"},"content":{"rendered":"<div id='companylogo'><img src='https:\/\/www.thailandcompanydirectory.com\/factory\/picture_not_available.jpg'><\/div>\n<div id='companyname'><span id='th_name'>\u0e2a\u0e21\u0e04\u0e34\u0e14\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e42\u0e14\u0e22\u0e19\u0e32\u0e07\u0e40\u0e1e\u0e47\u0e0d\u0e28\u0e23\u0e35 \u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21<\/span><br \/><span id='txt_name'> \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e41\u0e23\u0e48\u0e2d\u0e42\u0e2a\u0e2b\u0e30<\/span>  <\/div>\n<p><\/p>\n<div id='companydetail'>\n<div id='thaichar'><strong>\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 :<\/strong>  \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e41\u0e23\u0e48\u0e2d\u0e42\u0e2a\u0e2b\u0e30<\/div>\n<div id='thaichar'><strong>\u0e02\u0e19\u0e32\u0e14\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 :<\/strong> \u0e2d\u0e37\u0e48\u0e19\u0e46<\/div>\n<div id='thaichar'><strong>\u0e2a\u0e16\u0e32\u0e19\u0e20\u0e32\u0e1e\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 :<\/strong> \u0e22\u0e31\u0e07\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e22\u0e39\u0e48<\/div>\n<div id='thaichar'><strong>\u0e17\u0e35\u0e48\u0e15\u0e31\u0e49\u0e07 :<\/strong> 42 \u0e2b\u0e21\u0e39\u0e48 8 \u0e15\u0e33\u0e1a\u0e25\u0e42\u0e19\u0e19\u0e1b\u0e2d\u0e41\u0e14\u0e07 \u0e2d.\u0e1c\u0e32\u0e02\u0e32\u0e27 \u0e40\u0e25\u0e22 42240 <\/div>\n<div id='thaichar'><strong>\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c :<\/strong> 042-818106<\/div>\n<div id='thaichar'><strong>\u0e42\u0e17\u0e23\u0e2a\u0e32\u0e23 :<\/strong> n\/a<\/div>\n<div id='thaichar'><strong>\u0e2d\u0e35\u0e40\u0e21\u0e25\u0e25\u0e4c :<\/strong> n\/a<\/div>\n<div id='thaichar'><strong>\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e17\u0e4c :<\/strong> n\/a<\/div>\n<\/div>\n<p><\/p>\n<div>\n<div id='thaichar'>\n<p><strong>\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \/ \u0e15\u0e23\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \/ \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 :<\/strong> <\/p>\n<p><img alt='\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e22\u0e35\u0e48\u0e2b\u0e49\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32, \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c, \u0e15\u0e23\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e2d\u0e35\u0e40\u0e21\u0e25\u0e4c sales(at)thailandcompanydirectory.com' src='https:\/\/www.thailandcompanydirectory.com\/picture_not_available2.jpg'> <img alt='\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e22\u0e35\u0e48\u0e2b\u0e49\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32, \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c, \u0e15\u0e23\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e2d\u0e35\u0e40\u0e21\u0e25\u0e4c sales(at)thailandcompanydirectory.com' src='https:\/\/www.thailandcompanydirectory.com\/picture_not_available2.jpg'> <img alt='\u0e42\u0e06\u0e29\u0e13\u0e32 \u0e22\u0e35\u0e48\u0e2b\u0e49\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32, \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c, \u0e15\u0e23\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e2d\u0e35\u0e40\u0e21\u0e25\u0e4c sales(at)thailandcompanydirectory.com' src='https:\/\/www.thailandcompanydirectory.com\/picture_not_available2.jpg'><\/p>\n<p>\u0e2a\u0e19\u0e43\u0e08\u0e25\u0e07\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32, \u0e25\u0e07\u0e42\u0e06\u0e29\u0e13\u0e32, \u0e22\u0e35\u0e48\u0e2b\u0e49\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32, \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c, \u0e15\u0e23\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32  \u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e2d\u0e35\u0e40\u0e21\u0e25\u0e4c sales(at)thailandcompanydirectory.com<\/p>\n<\/div>\n<\/div>\n<p>\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07 \/ \u0e41\u0e1c\u0e19\u0e17\u0e35\u0e48 \u0e2a\u0e21\u0e04\u0e34\u0e14\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e42\u0e14\u0e22\u0e19\u0e32\u0e07\u0e40\u0e1e\u0e47\u0e0d\u0e28\u0e23\u0e35 \u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21<br \/><iframe width='700' height='400' frameborder='0' src='https:\/\/maps.google.com\/maps?&#038;q=\u0e2a\u0e21\u0e04\u0e34\u0e14\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15+\u0e42\u0e14\u0e22\u0e19\u0e32\u0e07\u0e40\u0e1e\u0e47\u0e0d\u0e28\u0e23\u0e35+\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21+\u0e40\u0e25\u0e22&#038;output=embed' marginwidth='0' marginheight='0' scrolling='no'><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e2a\u0e21\u0e04\u0e34\u0e14\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e42\u0e14\u0e22\u0e19\u0e32\u0e07\u0e40\u0e1e\u0e47\u0e0d\u0e28\u0e23\u0e35 \u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 \u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e04\u0e2d\u0e19\u0e01\u0e23<\/p>\n","protected":false},"author":1,"featured_media":62341,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[170],"tags":[171,78,91],"class_list":{"0":"post-47997","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-170","8":"tag-171","9":"tag-78","10":"tag-91"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e2a\u0e21\u0e04\u0e34\u0e14\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e42\u0e14\u0e22\u0e19\u0e32\u0e07\u0e40\u0e1e\u0e47\u0e0d\u0e28\u0e23\u0e35 \u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 - \u0e40\u0e25\u0e22 &#187; \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22<\/title>\n<meta name=\"description\" content=\"\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e2a\u0e21\u0e04\u0e34\u0e14\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e42\u0e14\u0e22\u0e19\u0e32\u0e07\u0e40\u0e1e\u0e47\u0e0d\u0e28\u0e23\u0e35 \u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 - \u0e40\u0e25\u0e22 \u0e04\u0e49\u0e19\u0e2b\u0e32\u0e43\u0e19 \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e43\u0e2b\u0e49\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e17\u0e31\u0e49\u0e07 \u0e07\u0e32\u0e19 \u0e41\u0e1c\u0e19\u0e17\u0e35\u0e48 \u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e42\u0e17\u0e23 \u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e41\u0e1f\u0e01\u0e0b\u0e4c \u0e40\u0e1f\u0e0b\u0e1a\u0e38\u0e4a\u0e04\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thailandcompanydirectory.com\/factory\/\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\/\u0e2a\u0e21\u0e04\u0e34\u0e14\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15-\u0e42\u0e14\u0e22\u0e19\u0e32\u0e07\u0e40\u0e1e\u0e47\u0e0d\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e2a\u0e21\u0e04\u0e34\u0e14\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e42\u0e14\u0e22\u0e19\u0e32\u0e07\u0e40\u0e1e\u0e47\u0e0d\u0e28\u0e23\u0e35 \u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 - \u0e40\u0e25\u0e22 &#187; \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\" \/>\n<meta property=\"og:description\" content=\"\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e2a\u0e21\u0e04\u0e34\u0e14\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e42\u0e14\u0e22\u0e19\u0e32\u0e07\u0e40\u0e1e\u0e47\u0e0d\u0e28\u0e23\u0e35 \u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 - \u0e40\u0e25\u0e22 \u0e04\u0e49\u0e19\u0e2b\u0e32\u0e43\u0e19 \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e43\u0e2b\u0e49\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e17\u0e31\u0e49\u0e07 \u0e07\u0e32\u0e19 \u0e41\u0e1c\u0e19\u0e17\u0e35\u0e48 \u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e42\u0e17\u0e23 \u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e41\u0e1f\u0e01\u0e0b\u0e4c \u0e40\u0e1f\u0e0b\u0e1a\u0e38\u0e4a\u0e04\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thailandcompanydirectory.com\/factory\/\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\/\u0e2a\u0e21\u0e04\u0e34\u0e14\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15-\u0e42\u0e14\u0e22\u0e19\u0e32\u0e07\u0e40\u0e1e\u0e47\u0e0d\" \/>\n<meta property=\"og:site_name\" content=\"\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-13T05:08:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.thailandcompanydirectory.com\/factory\/wp-content\/uploads\/2019\/06\/factory-images107.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"355\" \/>\n\t<meta property=\"og:image:height\" content=\"355\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.thailandcompanydirectory.com\\\/factory\\\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5\\\/%e0%b8%aa%e0%b8%a1%e0%b8%84%e0%b8%b4%e0%b8%94%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%95-%e0%b9%82%e0%b8%94%e0%b8%a2%e0%b8%99%e0%b8%b2%e0%b8%87%e0%b9%80%e0%b8%9e%e0%b9%87%e0%b8%8d#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.thailandcompanydirectory.com\\\/factory\\\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5\\\/%e0%b8%aa%e0%b8%a1%e0%b8%84%e0%b8%b4%e0%b8%94%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%95-%e0%b9%82%e0%b8%94%e0%b8%a2%e0%b8%99%e0%b8%b2%e0%b8%87%e0%b9%80%e0%b8%9e%e0%b9%87%e0%b8%8d\"},\"author\":{\"name\":\"\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\",\"@id\":\"https:\\\/\\\/www.thailandcompanydirectory.com\\\/factory\\\/#\\\/schema\\\/person\\\/8da0b83bbae4281a2cf61b37613e1859\"},\"headline\":\"\u0e2a\u0e21\u0e04\u0e34\u0e14\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e42\u0e14\u0e22\u0e19\u0e32\u0e07\u0e40\u0e1e\u0e47\u0e0d\u0e28\u0e23\u0e35 \u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 &#8211; \u0e40\u0e25\u0e22\",\"datePublished\":\"2016-10-13T05:08:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.thailandcompanydirectory.com\\\/factory\\\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5\\\/%e0%b8%aa%e0%b8%a1%e0%b8%84%e0%b8%b4%e0%b8%94%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%95-%e0%b9%82%e0%b8%94%e0%b8%a2%e0%b8%99%e0%b8%b2%e0%b8%87%e0%b9%80%e0%b8%9e%e0%b9%87%e0%b8%8d\"},\"wordCount\":12,\"publisher\":{\"@id\":\"https:\\\/\\\/www.thailandcompanydirectory.com\\\/factory\\\/#\\\/schema\\\/person\\\/8da0b83bbae4281a2cf61b37613e1859\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thailandcompanydirectory.com\\\/factory\\\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5\\\/%e0%b8%aa%e0%b8%a1%e0%b8%84%e0%b8%b4%e0%b8%94%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%95-%e0%b9%82%e0%b8%94%e0%b8%a2%e0%b8%99%e0%b8%b2%e0%b8%87%e0%b9%80%e0%b8%9e%e0%b9%87%e0%b8%8d#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.thailandcompanydirectory.com\\\/factory\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/factory-images107.jpg\",\"keywords\":[\"\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\u0e2d\u0e31\u0e14\u0e41\u0e23\u0e07\",\"\u0e2d\u0e37\u0e48\u0e19\u0e46\",\"\u0e40\u0e25\u0e22\"],\"articleSection\":[\"\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\u0e2d\u0e31\u0e14\u0e41\u0e23\u0e07\"],\"inLanguage\":\"th\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.thailandcompanydirectory.com\\\/factory\\\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5\\\/%e0%b8%aa%e0%b8%a1%e0%b8%84%e0%b8%b4%e0%b8%94%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%95-%e0%b9%82%e0%b8%94%e0%b8%a2%e0%b8%99%e0%b8%b2%e0%b8%87%e0%b9%80%e0%b8%9e%e0%b9%87%e0%b8%8d\",\"url\":\"https:\\\/\\\/www.thailandcompanydirectory.com\\\/factory\\\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5\\\/%e0%b8%aa%e0%b8%a1%e0%b8%84%e0%b8%b4%e0%b8%94%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%95-%e0%b9%82%e0%b8%94%e0%b8%a2%e0%b8%99%e0%b8%b2%e0%b8%87%e0%b9%80%e0%b8%9e%e0%b9%87%e0%b8%8d\",\"name\":\"\u0e2a\u0e21\u0e04\u0e34\u0e14\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e42\u0e14\u0e22\u0e19\u0e32\u0e07\u0e40\u0e1e\u0e47\u0e0d\u0e28\u0e23\u0e35 \u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 - \u0e40\u0e25\u0e22 &#187; \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.thailandcompanydirectory.com\\\/factory\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.thailandcompanydirectory.com\\\/factory\\\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5\\\/%e0%b8%aa%e0%b8%a1%e0%b8%84%e0%b8%b4%e0%b8%94%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%95-%e0%b9%82%e0%b8%94%e0%b8%a2%e0%b8%99%e0%b8%b2%e0%b8%87%e0%b9%80%e0%b8%9e%e0%b9%87%e0%b8%8d#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thailandcompanydirectory.com\\\/factory\\\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5\\\/%e0%b8%aa%e0%b8%a1%e0%b8%84%e0%b8%b4%e0%b8%94%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%95-%e0%b9%82%e0%b8%94%e0%b8%a2%e0%b8%99%e0%b8%b2%e0%b8%87%e0%b9%80%e0%b8%9e%e0%b9%87%e0%b8%8d#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.thailandcompanydirectory.com\\\/factory\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/factory-images107.jpg\",\"datePublished\":\"2016-10-13T05:08:46+00:00\",\"description\":\"\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e2a\u0e21\u0e04\u0e34\u0e14\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e42\u0e14\u0e22\u0e19\u0e32\u0e07\u0e40\u0e1e\u0e47\u0e0d\u0e28\u0e23\u0e35 \u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 - \u0e40\u0e25\u0e22 \u0e04\u0e49\u0e19\u0e2b\u0e32\u0e43\u0e19 \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e43\u0e2b\u0e49\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e17\u0e31\u0e49\u0e07 \u0e07\u0e32\u0e19 \u0e41\u0e1c\u0e19\u0e17\u0e35\u0e48 \u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e42\u0e17\u0e23 \u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e41\u0e1f\u0e01\u0e0b\u0e4c \u0e40\u0e1f\u0e0b\u0e1a\u0e38\u0e4a\u0e04\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.thailandcompanydirectory.com\\\/factory\\\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5\\\/%e0%b8%aa%e0%b8%a1%e0%b8%84%e0%b8%b4%e0%b8%94%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%95-%e0%b9%82%e0%b8%94%e0%b8%a2%e0%b8%99%e0%b8%b2%e0%b8%87%e0%b9%80%e0%b8%9e%e0%b9%87%e0%b8%8d#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.thailandcompanydirectory.com\\\/factory\\\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5\\\/%e0%b8%aa%e0%b8%a1%e0%b8%84%e0%b8%b4%e0%b8%94%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%95-%e0%b9%82%e0%b8%94%e0%b8%a2%e0%b8%99%e0%b8%b2%e0%b8%87%e0%b9%80%e0%b8%9e%e0%b9%87%e0%b8%8d\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.thailandcompanydirectory.com\\\/factory\\\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5\\\/%e0%b8%aa%e0%b8%a1%e0%b8%84%e0%b8%b4%e0%b8%94%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%95-%e0%b9%82%e0%b8%94%e0%b8%a2%e0%b8%99%e0%b8%b2%e0%b8%87%e0%b9%80%e0%b8%9e%e0%b9%87%e0%b8%8d#primaryimage\",\"url\":\"https:\\\/\\\/www.thailandcompanydirectory.com\\\/factory\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/factory-images107.jpg\",\"contentUrl\":\"https:\\\/\\\/www.thailandcompanydirectory.com\\\/factory\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/factory-images107.jpg\",\"width\":355,\"height\":355},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.thailandcompanydirectory.com\\\/factory\\\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5\\\/%e0%b8%aa%e0%b8%a1%e0%b8%84%e0%b8%b4%e0%b8%94%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%95-%e0%b9%82%e0%b8%94%e0%b8%a2%e0%b8%99%e0%b8%b2%e0%b8%87%e0%b9%80%e0%b8%9e%e0%b9%87%e0%b8%8d#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.thailandcompanydirectory.com\\\/factory\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e2a\u0e21\u0e04\u0e34\u0e14\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e42\u0e14\u0e22\u0e19\u0e32\u0e07\u0e40\u0e1e\u0e47\u0e0d\u0e28\u0e23\u0e35 \u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 &#8211; \u0e40\u0e25\u0e22\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.thailandcompanydirectory.com\\\/factory\\\/#website\",\"url\":\"https:\\\/\\\/www.thailandcompanydirectory.com\\\/factory\\\/\",\"name\":\"\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\",\"description\":\"Thailand Factory Directory Listing\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.thailandcompanydirectory.com\\\/factory\\\/#\\\/schema\\\/person\\\/8da0b83bbae4281a2cf61b37613e1859\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.thailandcompanydirectory.com\\\/factory\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.thailandcompanydirectory.com\\\/factory\\\/#\\\/schema\\\/person\\\/8da0b83bbae4281a2cf61b37613e1859\",\"name\":\"\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/034d3e3581ee92f083c99fe8095ef9e0fb28fddb6cc0b98354701621db5a22a4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/034d3e3581ee92f083c99fe8095ef9e0fb28fddb6cc0b98354701621db5a22a4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/034d3e3581ee92f083c99fe8095ef9e0fb28fddb6cc0b98354701621db5a22a4?s=96&d=mm&r=g\",\"caption\":\"\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/034d3e3581ee92f083c99fe8095ef9e0fb28fddb6cc0b98354701621db5a22a4?s=96&d=mm&r=g\"},\"description\":\"\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2b\u0e32 \u0e07\u0e32\u0e19 \u0e2b\u0e32\u0e07\u0e32\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e02\u0e2d\u0e07 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e17\u0e35\u0e48\u0e17\u0e48\u0e32\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21\u0e21\u0e32\u0e44\u0e27\u0e49\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48\u0e41\u0e25\u0e49\u0e27 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e02\u0e2d\u0e07\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e19\u0e33\u0e44\u0e1b\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d \u0e2b\u0e23\u0e37\u0e2d \u0e17\u0e33\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e44\u0e14\u0e49 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e44\u0e17\u0e22 \u0e23\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e2d\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e2a\u0e21\u0e04\u0e34\u0e14\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e42\u0e14\u0e22\u0e19\u0e32\u0e07\u0e40\u0e1e\u0e47\u0e0d\u0e28\u0e23\u0e35 \u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 - \u0e40\u0e25\u0e22 &#187; \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22","description":"\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e2a\u0e21\u0e04\u0e34\u0e14\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e42\u0e14\u0e22\u0e19\u0e32\u0e07\u0e40\u0e1e\u0e47\u0e0d\u0e28\u0e23\u0e35 \u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 - \u0e40\u0e25\u0e22 \u0e04\u0e49\u0e19\u0e2b\u0e32\u0e43\u0e19 \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e43\u0e2b\u0e49\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e17\u0e31\u0e49\u0e07 \u0e07\u0e32\u0e19 \u0e41\u0e1c\u0e19\u0e17\u0e35\u0e48 \u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e42\u0e17\u0e23 \u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e41\u0e1f\u0e01\u0e0b\u0e4c \u0e40\u0e1f\u0e0b\u0e1a\u0e38\u0e4a\u0e04","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thailandcompanydirectory.com\/factory\/\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\/\u0e2a\u0e21\u0e04\u0e34\u0e14\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15-\u0e42\u0e14\u0e22\u0e19\u0e32\u0e07\u0e40\u0e1e\u0e47\u0e0d","og_locale":"th_TH","og_type":"article","og_title":"\u0e2a\u0e21\u0e04\u0e34\u0e14\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e42\u0e14\u0e22\u0e19\u0e32\u0e07\u0e40\u0e1e\u0e47\u0e0d\u0e28\u0e23\u0e35 \u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 - \u0e40\u0e25\u0e22 &#187; \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22","og_description":"\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e2a\u0e21\u0e04\u0e34\u0e14\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e42\u0e14\u0e22\u0e19\u0e32\u0e07\u0e40\u0e1e\u0e47\u0e0d\u0e28\u0e23\u0e35 \u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 - \u0e40\u0e25\u0e22 \u0e04\u0e49\u0e19\u0e2b\u0e32\u0e43\u0e19 \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e43\u0e2b\u0e49\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e17\u0e31\u0e49\u0e07 \u0e07\u0e32\u0e19 \u0e41\u0e1c\u0e19\u0e17\u0e35\u0e48 \u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e42\u0e17\u0e23 \u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e41\u0e1f\u0e01\u0e0b\u0e4c \u0e40\u0e1f\u0e0b\u0e1a\u0e38\u0e4a\u0e04","og_url":"https:\/\/www.thailandcompanydirectory.com\/factory\/\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\/\u0e2a\u0e21\u0e04\u0e34\u0e14\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15-\u0e42\u0e14\u0e22\u0e19\u0e32\u0e07\u0e40\u0e1e\u0e47\u0e0d","og_site_name":"\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22","article_published_time":"2016-10-13T05:08:46+00:00","og_image":[{"width":355,"height":355,"url":"https:\/\/www.thailandcompanydirectory.com\/factory\/wp-content\/uploads\/2019\/06\/factory-images107.jpg","type":"image\/jpeg"}],"author":"\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21","twitter_card":"summary_large_image","twitter_misc":{"Written by":"\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.thailandcompanydirectory.com\/factory\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5\/%e0%b8%aa%e0%b8%a1%e0%b8%84%e0%b8%b4%e0%b8%94%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%95-%e0%b9%82%e0%b8%94%e0%b8%a2%e0%b8%99%e0%b8%b2%e0%b8%87%e0%b9%80%e0%b8%9e%e0%b9%87%e0%b8%8d#article","isPartOf":{"@id":"https:\/\/www.thailandcompanydirectory.com\/factory\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5\/%e0%b8%aa%e0%b8%a1%e0%b8%84%e0%b8%b4%e0%b8%94%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%95-%e0%b9%82%e0%b8%94%e0%b8%a2%e0%b8%99%e0%b8%b2%e0%b8%87%e0%b9%80%e0%b8%9e%e0%b9%87%e0%b8%8d"},"author":{"name":"\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21","@id":"https:\/\/www.thailandcompanydirectory.com\/factory\/#\/schema\/person\/8da0b83bbae4281a2cf61b37613e1859"},"headline":"\u0e2a\u0e21\u0e04\u0e34\u0e14\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e42\u0e14\u0e22\u0e19\u0e32\u0e07\u0e40\u0e1e\u0e47\u0e0d\u0e28\u0e23\u0e35 \u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 &#8211; \u0e40\u0e25\u0e22","datePublished":"2016-10-13T05:08:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.thailandcompanydirectory.com\/factory\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5\/%e0%b8%aa%e0%b8%a1%e0%b8%84%e0%b8%b4%e0%b8%94%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%95-%e0%b9%82%e0%b8%94%e0%b8%a2%e0%b8%99%e0%b8%b2%e0%b8%87%e0%b9%80%e0%b8%9e%e0%b9%87%e0%b8%8d"},"wordCount":12,"publisher":{"@id":"https:\/\/www.thailandcompanydirectory.com\/factory\/#\/schema\/person\/8da0b83bbae4281a2cf61b37613e1859"},"image":{"@id":"https:\/\/www.thailandcompanydirectory.com\/factory\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5\/%e0%b8%aa%e0%b8%a1%e0%b8%84%e0%b8%b4%e0%b8%94%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%95-%e0%b9%82%e0%b8%94%e0%b8%a2%e0%b8%99%e0%b8%b2%e0%b8%87%e0%b9%80%e0%b8%9e%e0%b9%87%e0%b8%8d#primaryimage"},"thumbnailUrl":"https:\/\/www.thailandcompanydirectory.com\/factory\/wp-content\/uploads\/2019\/06\/factory-images107.jpg","keywords":["\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\u0e2d\u0e31\u0e14\u0e41\u0e23\u0e07","\u0e2d\u0e37\u0e48\u0e19\u0e46","\u0e40\u0e25\u0e22"],"articleSection":["\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\u0e2d\u0e31\u0e14\u0e41\u0e23\u0e07"],"inLanguage":"th"},{"@type":"WebPage","@id":"https:\/\/www.thailandcompanydirectory.com\/factory\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5\/%e0%b8%aa%e0%b8%a1%e0%b8%84%e0%b8%b4%e0%b8%94%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%95-%e0%b9%82%e0%b8%94%e0%b8%a2%e0%b8%99%e0%b8%b2%e0%b8%87%e0%b9%80%e0%b8%9e%e0%b9%87%e0%b8%8d","url":"https:\/\/www.thailandcompanydirectory.com\/factory\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5\/%e0%b8%aa%e0%b8%a1%e0%b8%84%e0%b8%b4%e0%b8%94%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%95-%e0%b9%82%e0%b8%94%e0%b8%a2%e0%b8%99%e0%b8%b2%e0%b8%87%e0%b9%80%e0%b8%9e%e0%b9%87%e0%b8%8d","name":"\u0e2a\u0e21\u0e04\u0e34\u0e14\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e42\u0e14\u0e22\u0e19\u0e32\u0e07\u0e40\u0e1e\u0e47\u0e0d\u0e28\u0e23\u0e35 \u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 - \u0e40\u0e25\u0e22 &#187; \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22","isPartOf":{"@id":"https:\/\/www.thailandcompanydirectory.com\/factory\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thailandcompanydirectory.com\/factory\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5\/%e0%b8%aa%e0%b8%a1%e0%b8%84%e0%b8%b4%e0%b8%94%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%95-%e0%b9%82%e0%b8%94%e0%b8%a2%e0%b8%99%e0%b8%b2%e0%b8%87%e0%b9%80%e0%b8%9e%e0%b9%87%e0%b8%8d#primaryimage"},"image":{"@id":"https:\/\/www.thailandcompanydirectory.com\/factory\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5\/%e0%b8%aa%e0%b8%a1%e0%b8%84%e0%b8%b4%e0%b8%94%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%95-%e0%b9%82%e0%b8%94%e0%b8%a2%e0%b8%99%e0%b8%b2%e0%b8%87%e0%b9%80%e0%b8%9e%e0%b9%87%e0%b8%8d#primaryimage"},"thumbnailUrl":"https:\/\/www.thailandcompanydirectory.com\/factory\/wp-content\/uploads\/2019\/06\/factory-images107.jpg","datePublished":"2016-10-13T05:08:46+00:00","description":"\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e2a\u0e21\u0e04\u0e34\u0e14\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e42\u0e14\u0e22\u0e19\u0e32\u0e07\u0e40\u0e1e\u0e47\u0e0d\u0e28\u0e23\u0e35 \u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 - \u0e40\u0e25\u0e22 \u0e04\u0e49\u0e19\u0e2b\u0e32\u0e43\u0e19 \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e43\u0e2b\u0e49\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e17\u0e31\u0e49\u0e07 \u0e07\u0e32\u0e19 \u0e41\u0e1c\u0e19\u0e17\u0e35\u0e48 \u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e42\u0e17\u0e23 \u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e41\u0e1f\u0e01\u0e0b\u0e4c \u0e40\u0e1f\u0e0b\u0e1a\u0e38\u0e4a\u0e04","breadcrumb":{"@id":"https:\/\/www.thailandcompanydirectory.com\/factory\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5\/%e0%b8%aa%e0%b8%a1%e0%b8%84%e0%b8%b4%e0%b8%94%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%95-%e0%b9%82%e0%b8%94%e0%b8%a2%e0%b8%99%e0%b8%b2%e0%b8%87%e0%b9%80%e0%b8%9e%e0%b9%87%e0%b8%8d#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thailandcompanydirectory.com\/factory\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5\/%e0%b8%aa%e0%b8%a1%e0%b8%84%e0%b8%b4%e0%b8%94%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%95-%e0%b9%82%e0%b8%94%e0%b8%a2%e0%b8%99%e0%b8%b2%e0%b8%87%e0%b9%80%e0%b8%9e%e0%b9%87%e0%b8%8d"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.thailandcompanydirectory.com\/factory\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5\/%e0%b8%aa%e0%b8%a1%e0%b8%84%e0%b8%b4%e0%b8%94%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%95-%e0%b9%82%e0%b8%94%e0%b8%a2%e0%b8%99%e0%b8%b2%e0%b8%87%e0%b9%80%e0%b8%9e%e0%b9%87%e0%b8%8d#primaryimage","url":"https:\/\/www.thailandcompanydirectory.com\/factory\/wp-content\/uploads\/2019\/06\/factory-images107.jpg","contentUrl":"https:\/\/www.thailandcompanydirectory.com\/factory\/wp-content\/uploads\/2019\/06\/factory-images107.jpg","width":355,"height":355},{"@type":"BreadcrumbList","@id":"https:\/\/www.thailandcompanydirectory.com\/factory\/%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%9c%e0%b8%a5%e0%b8%b4%e0%b8%95%e0%b8%a0%e0%b8%b1%e0%b8%93%e0%b8%91%e0%b9%8c%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5\/%e0%b8%aa%e0%b8%a1%e0%b8%84%e0%b8%b4%e0%b8%94%e0%b8%84%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%95-%e0%b9%82%e0%b8%94%e0%b8%a2%e0%b8%99%e0%b8%b2%e0%b8%87%e0%b9%80%e0%b8%9e%e0%b9%87%e0%b8%8d#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.thailandcompanydirectory.com\/factory\/"},{"@type":"ListItem","position":2,"name":"\u0e2a\u0e21\u0e04\u0e34\u0e14\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15 \u0e42\u0e14\u0e22\u0e19\u0e32\u0e07\u0e40\u0e1e\u0e47\u0e0d\u0e28\u0e23\u0e35 \u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21 &#8211; \u0e40\u0e25\u0e22"}]},{"@type":"WebSite","@id":"https:\/\/www.thailandcompanydirectory.com\/factory\/#website","url":"https:\/\/www.thailandcompanydirectory.com\/factory\/","name":"\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22","description":"Thailand Factory Directory Listing","publisher":{"@id":"https:\/\/www.thailandcompanydirectory.com\/factory\/#\/schema\/person\/8da0b83bbae4281a2cf61b37613e1859"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thailandcompanydirectory.com\/factory\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":["Person","Organization"],"@id":"https:\/\/www.thailandcompanydirectory.com\/factory\/#\/schema\/person\/8da0b83bbae4281a2cf61b37613e1859","name":"\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/secure.gravatar.com\/avatar\/034d3e3581ee92f083c99fe8095ef9e0fb28fddb6cc0b98354701621db5a22a4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/034d3e3581ee92f083c99fe8095ef9e0fb28fddb6cc0b98354701621db5a22a4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/034d3e3581ee92f083c99fe8095ef9e0fb28fddb6cc0b98354701621db5a22a4?s=96&d=mm&r=g","caption":"\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/034d3e3581ee92f083c99fe8095ef9e0fb28fddb6cc0b98354701621db5a22a4?s=96&d=mm&r=g"},"description":"\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2b\u0e32 \u0e07\u0e32\u0e19 \u0e2b\u0e32\u0e07\u0e32\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e02\u0e2d\u0e07 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e17\u0e35\u0e48\u0e17\u0e48\u0e32\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21\u0e21\u0e32\u0e44\u0e27\u0e49\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48\u0e41\u0e25\u0e49\u0e27 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e02\u0e2d\u0e07\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e19\u0e33\u0e44\u0e1b\u0e40\u0e1b\u0e47\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d \u0e2b\u0e23\u0e37\u0e2d \u0e17\u0e33\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e44\u0e14\u0e49 \u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e44\u0e17\u0e22 \u0e23\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e2d\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.thailandcompanydirectory.com\/factory\/wp-json\/wp\/v2\/posts\/47997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thailandcompanydirectory.com\/factory\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thailandcompanydirectory.com\/factory\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thailandcompanydirectory.com\/factory\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thailandcompanydirectory.com\/factory\/wp-json\/wp\/v2\/comments?post=47997"}],"version-history":[{"count":0,"href":"https:\/\/www.thailandcompanydirectory.com\/factory\/wp-json\/wp\/v2\/posts\/47997\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.thailandcompanydirectory.com\/factory\/wp-json\/wp\/v2\/media\/62341"}],"wp:attachment":[{"href":"https:\/\/www.thailandcompanydirectory.com\/factory\/wp-json\/wp\/v2\/media?parent=47997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thailandcompanydirectory.com\/factory\/wp-json\/wp\/v2\/categories?post=47997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thailandcompanydirectory.com\/factory\/wp-json\/wp\/v2\/tags?post=47997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}